{"id":156703,"date":"2025-01-24T09:37:50","date_gmt":"2025-01-24T09:37:50","guid":{"rendered":"https:\/\/pro.cardamomo.com\/es\/?page_id=156703"},"modified":"2026-05-22T12:40:36","modified_gmt":"2026-05-22T10:40:36","slug":"entradas-especiales","status":"publish","type":"page","link":"https:\/\/cardamomo.com\/it\/entradas-especiales\/","title":{"rendered":"Biglietti speciali"},"content":{"rendered":"<p>Qui troverai le informazioni sui biglietti speciali disponibili al Cardamomo: posti per <strong>persone con mobilit\u00e0 ridotta<\/strong>, <strong>biglietti per bambini<\/strong>, biglietti per <strong>residenti<\/strong> o <strong>posti in promozione<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"Qui troverai le informazioni sui biglietti speciali disponibili al Cardamomo: posti per persone con mobilit\u00e0 ridotta, biglietti per bambini, biglietti per residenti o posti in promozione.","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-156703","page","type-page","status-publish","hentry"],"acf":{"display":"reduced","hero_intro":"Tutti sono i benvenuti al Cardamomo","hero_heading":"h2","generic_slider":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biglietti speciali - Cardamomo Flamenco Madrid<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biglietti speciali - Cardamomo Flamenco Madrid\" \/>\n<meta property=\"og:description\" content=\"Qui troverai le informazioni sui biglietti speciali disponibili al Cardamomo: posti per persone con mobilit\u00e0 ridotta, biglietti per bambini, biglietti per residenti o posti in promozione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cardamomo.com\/it\/entradas-especiales\/\" \/>\n<meta property=\"og:site_name\" content=\"Cardamomo Flamenco Madrid\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T10:40:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/entradas-especiales\\\/\",\"url\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/entradas-especiales\\\/\",\"name\":\"Biglietti speciali - Cardamomo Flamenco Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/#website\"},\"datePublished\":\"2025-01-24T09:37:50+00:00\",\"dateModified\":\"2026-05-22T10:40:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/entradas-especiales\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/cardamomo.com\\\/it\\\/entradas-especiales\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/entradas-especiales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cardamomo\",\"item\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entradas especiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/\",\"name\":\"Cardamomo Flamenco Madrid\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cardamomo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biglietti speciali - Cardamomo Flamenco Madrid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"it_IT","og_type":"article","og_title":"Biglietti speciali - Cardamomo Flamenco Madrid","og_description":"Qui troverai le informazioni sui biglietti speciali disponibili al Cardamomo: posti per persone con mobilit\u00e0 ridotta, biglietti per bambini, biglietti per residenti o posti in promozione.","og_url":"https:\/\/cardamomo.com\/it\/entradas-especiales\/","og_site_name":"Cardamomo Flamenco Madrid","article_modified_time":"2026-05-22T10:40:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cardamomo.com\/it\/entradas-especiales\/","url":"https:\/\/cardamomo.com\/it\/entradas-especiales\/","name":"Biglietti speciali - Cardamomo Flamenco Madrid","isPartOf":{"@id":"https:\/\/cardamomo.com\/it\/#website"},"datePublished":"2025-01-24T09:37:50+00:00","dateModified":"2026-05-22T10:40:36+00:00","breadcrumb":{"@id":"https:\/\/cardamomo.com\/it\/entradas-especiales\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/cardamomo.com\/it\/entradas-especiales\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cardamomo.com\/it\/entradas-especiales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cardamomo","item":"https:\/\/cardamomo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Entradas especiales"}]},{"@type":"WebSite","@id":"https:\/\/cardamomo.com\/it\/#website","url":"https:\/\/cardamomo.com\/it\/","name":"Cardamomo Flamenco Madrid","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cardamomo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/pages\/156703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/comments?post=156703"}],"version-history":[{"count":57,"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/pages\/156703\/revisions"}],"predecessor-version":[{"id":159087,"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/pages\/156703\/revisions\/159087"}],"wp:attachment":[{"href":"https:\/\/cardamomo.com\/it\/wp-json\/wp\/v2\/media?parent=156703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}